{"id":639,"count":10,"description":"","link":"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/","name":"\ud83d\udc64 Telefon n\u00f6mr\u0259si s\u0259hif\u0259si","slug":"phone-number-page-iphone","taxonomy":"help_category","parent":632,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ud83d\udc64 Telefon n\u00f6mr\u0259si s\u0259hif\u0259si - NumBuster<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/\" \/>\n<meta property=\"og:locale\" content=\"az_AZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\udc64 Telefon n\u00f6mr\u0259si s\u0259hif\u0259si - NumBuster\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/\" \/>\n<meta property=\"og:site_name\" content=\"NumBuster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/\",\"url\":\"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/\",\"name\":\"\ud83d\udc64 Telefon n\u00f6mr\u0259si s\u0259hif\u0259si - NumBuster\",\"isPartOf\":{\"@id\":\"https:\/\/numbuster.com\/tr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/#breadcrumb\"},\"inLanguage\":\"az\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/numbuster.me\/az\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"iPhone\",\"item\":\"https:\/\/truenmbstapp.de\/az\/help\/iphone\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\ud83d\udc64 Telefon n\u00f6mr\u0259si s\u0259hif\u0259si\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/truenmbstapp.de\/az\/#website\",\"url\":\"https:\/\/truenmbstapp.de\/az\",\"name\":\"NumBuster\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/numbuster.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"az\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\udc64 Telefon n\u00f6mr\u0259si s\u0259hif\u0259si - NumBuster","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/","og_locale":"az_AZ","og_type":"article","og_title":"\ud83d\udc64 Telefon n\u00f6mr\u0259si s\u0259hif\u0259si - NumBuster","og_url":"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/","og_site_name":"NumBuster","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/","url":"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/","name":"\ud83d\udc64 Telefon n\u00f6mr\u0259si s\u0259hif\u0259si - NumBuster","isPartOf":{"@id":"https:\/\/numbuster.com\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/#breadcrumb"},"inLanguage":"az"},{"@type":"BreadcrumbList","@id":"https:\/\/truenmbstapp.de\/az\/help\/iphone\/phone-number-page-iphone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/numbuster.me\/az\/"},{"@type":"ListItem","position":2,"name":"iPhone","item":"https:\/\/truenmbstapp.de\/az\/help\/iphone\/"},{"@type":"ListItem","position":3,"name":"\ud83d\udc64 Telefon n\u00f6mr\u0259si s\u0259hif\u0259si"}]},{"@type":"WebSite","@id":"https:\/\/truenmbstapp.de\/az\/#website","url":"https:\/\/truenmbstapp.de\/az","name":"NumBuster","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numbuster.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"az"}]}},"_links":{"self":[{"href":"https:\/\/truenmbstapp.de\/az\/wp-json\/wp\/v2\/help_category\/639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truenmbstapp.de\/az\/wp-json\/wp\/v2\/help_category"}],"about":[{"href":"https:\/\/truenmbstapp.de\/az\/wp-json\/wp\/v2\/taxonomies\/help_category"}],"up":[{"embeddable":true,"href":"https:\/\/truenmbstapp.de\/az\/wp-json\/wp\/v2\/help_category\/632"}],"wp:post_type":[{"href":"https:\/\/truenmbstapp.de\/az\/wp-json\/wp\/v2\/help?help_category=639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}