{"id":340,"count":10,"description":"","link":"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/","name":"\ud83d\udc64 Phone number page","slug":"phone-number-page-android","taxonomy":"help_category","parent":27,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ud83d\udc64 Phone number page - NumBuster<\/title>\n<meta name=\"description\" content=\"Profile management in NumBuster: privacy settings, data editing, and profile visual customization.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\udc64 Phone number page - NumBuster\" \/>\n<meta property=\"og:description\" content=\"Profile management in NumBuster: privacy settings, data editing, and profile visual customization.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/\" \/>\n<meta property=\"og:site_name\" content=\"NumBuster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/\",\"url\":\"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/\",\"name\":\"\ud83d\udc64 Phone number page - NumBuster\",\"isPartOf\":{\"@id\":\"https:\/\/numbuster.com\/tr\/#website\"},\"description\":\"Profile management in NumBuster: privacy settings, data editing, and profile visual customization.\",\"breadcrumb\":{\"@id\":\"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/numbuster.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Android\",\"item\":\"https:\/\/truenmbstapp.de\/en\/help\/android\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\ud83d\udc64 Phone number page\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/truenmbstapp.de\/en\/#website\",\"url\":\"https:\/\/truenmbstapp.de\/en\",\"name\":\"NumBuster\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/numbuster.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\udc64 Phone number page - NumBuster","description":"Profile management in NumBuster: privacy settings, data editing, and profile visual customization.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/","og_locale":"en_US","og_type":"article","og_title":"\ud83d\udc64 Phone number page - NumBuster","og_description":"Profile management in NumBuster: privacy settings, data editing, and profile visual customization.","og_url":"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/","og_site_name":"NumBuster","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/","url":"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/","name":"\ud83d\udc64 Phone number page - NumBuster","isPartOf":{"@id":"https:\/\/numbuster.com\/tr\/#website"},"description":"Profile management in NumBuster: privacy settings, data editing, and profile visual customization.","breadcrumb":{"@id":"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/truenmbstapp.de\/en\/help\/android\/phone-number-page-android\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/numbuster.com\/en\/"},{"@type":"ListItem","position":2,"name":"Android","item":"https:\/\/truenmbstapp.de\/en\/help\/android\/"},{"@type":"ListItem","position":3,"name":"\ud83d\udc64 Phone number page"}]},{"@type":"WebSite","@id":"https:\/\/truenmbstapp.de\/en\/#website","url":"https:\/\/truenmbstapp.de\/en","name":"NumBuster","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numbuster.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/truenmbstapp.de\/en\/wp-json\/wp\/v2\/help_category\/340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truenmbstapp.de\/en\/wp-json\/wp\/v2\/help_category"}],"about":[{"href":"https:\/\/truenmbstapp.de\/en\/wp-json\/wp\/v2\/taxonomies\/help_category"}],"up":[{"embeddable":true,"href":"https:\/\/truenmbstapp.de\/en\/wp-json\/wp\/v2\/help_category\/27"}],"wp:post_type":[{"href":"https:\/\/truenmbstapp.de\/en\/wp-json\/wp\/v2\/help?help_category=340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}