{"id":735,"count":10,"description":"","link":"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/","name":"\ud83d\udc64 \u092b\u093c\u094b\u0928 \u0928\u0902\u092c\u0930 \u092a\u0947\u091c","slug":"phone-number-page-iphone","taxonomy":"help_category","parent":728,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ud83d\udc64 \u092b\u093c\u094b\u0928 \u0928\u0902\u092c\u0930 \u092a\u0947\u091c - NumBuster<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/\" \/>\n<meta property=\"og:locale\" content=\"hi_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\udc64 \u092b\u093c\u094b\u0928 \u0928\u0902\u092c\u0930 \u092a\u0947\u091c - NumBuster\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/\" \/>\n<meta property=\"og:site_name\" content=\"NumBuster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/\",\"url\":\"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/\",\"name\":\"\ud83d\udc64 \u092b\u093c\u094b\u0928 \u0928\u0902\u092c\u0930 \u092a\u0947\u091c - NumBuster\",\"isPartOf\":{\"@id\":\"https:\/\/numbuster.com\/tr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/#breadcrumb\"},\"inLanguage\":\"hi-IN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/numbuster.me\/hi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"iPhone\",\"item\":\"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\ud83d\udc64 \u092b\u093c\u094b\u0928 \u0928\u0902\u092c\u0930 \u092a\u0947\u091c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/truenmbstapp.de\/hi\/#website\",\"url\":\"https:\/\/truenmbstapp.de\/hi\",\"name\":\"NumBuster\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/numbuster.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hi-IN\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\udc64 \u092b\u093c\u094b\u0928 \u0928\u0902\u092c\u0930 \u092a\u0947\u091c - NumBuster","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/","og_locale":"hi_IN","og_type":"article","og_title":"\ud83d\udc64 \u092b\u093c\u094b\u0928 \u0928\u0902\u092c\u0930 \u092a\u0947\u091c - NumBuster","og_url":"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/","og_site_name":"NumBuster","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/","url":"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/","name":"\ud83d\udc64 \u092b\u093c\u094b\u0928 \u0928\u0902\u092c\u0930 \u092a\u0947\u091c - NumBuster","isPartOf":{"@id":"https:\/\/numbuster.com\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/#breadcrumb"},"inLanguage":"hi-IN"},{"@type":"BreadcrumbList","@id":"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/phone-number-page-iphone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/numbuster.me\/hi\/"},{"@type":"ListItem","position":2,"name":"iPhone","item":"https:\/\/truenmbstapp.de\/hi\/help\/iphone\/"},{"@type":"ListItem","position":3,"name":"\ud83d\udc64 \u092b\u093c\u094b\u0928 \u0928\u0902\u092c\u0930 \u092a\u0947\u091c"}]},{"@type":"WebSite","@id":"https:\/\/truenmbstapp.de\/hi\/#website","url":"https:\/\/truenmbstapp.de\/hi","name":"NumBuster","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numbuster.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hi-IN"}]}},"_links":{"self":[{"href":"https:\/\/truenmbstapp.de\/hi\/wp-json\/wp\/v2\/help_category\/735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truenmbstapp.de\/hi\/wp-json\/wp\/v2\/help_category"}],"about":[{"href":"https:\/\/truenmbstapp.de\/hi\/wp-json\/wp\/v2\/taxonomies\/help_category"}],"up":[{"embeddable":true,"href":"https:\/\/truenmbstapp.de\/hi\/wp-json\/wp\/v2\/help_category\/728"}],"wp:post_type":[{"href":"https:\/\/truenmbstapp.de\/hi\/wp-json\/wp\/v2\/help?help_category=735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}