{"id":750,"count":2,"description":"","link":"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/","name":"\ud83d\udd0d Periksa nomor telepon","slug":"check-phone-numbers-iphone","taxonomy":"help_category","parent":744,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ud83d\udd0d Periksa nomor telepon - NumBuster<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\udd0d Periksa nomor telepon - NumBuster\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/\" \/>\n<meta property=\"og:site_name\" content=\"NumBuster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/\",\"url\":\"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/\",\"name\":\"\ud83d\udd0d Periksa nomor telepon - NumBuster\",\"isPartOf\":{\"@id\":\"https:\/\/numbuster.com\/tr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/#breadcrumb\"},\"inLanguage\":\"id-ID\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/truenmbstapp.de\/id\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"iPhone\",\"item\":\"https:\/\/truenmbstapp.de\/id\/help\/iphone\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\ud83d\udd0d Periksa nomor telepon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/truenmbstapp.de\/id\/#website\",\"url\":\"https:\/\/truenmbstapp.de\/id\",\"name\":\"NumBuster\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/numbuster.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id-ID\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\udd0d Periksa nomor telepon - NumBuster","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/","og_locale":"id_ID","og_type":"article","og_title":"\ud83d\udd0d Periksa nomor telepon - NumBuster","og_url":"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/","og_site_name":"NumBuster","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/","url":"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/","name":"\ud83d\udd0d Periksa nomor telepon - NumBuster","isPartOf":{"@id":"https:\/\/numbuster.com\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/#breadcrumb"},"inLanguage":"id-ID"},{"@type":"BreadcrumbList","@id":"https:\/\/truenmbstapp.de\/id\/help\/iphone\/check-phone-numbers-iphone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/truenmbstapp.de\/id\/"},{"@type":"ListItem","position":2,"name":"iPhone","item":"https:\/\/truenmbstapp.de\/id\/help\/iphone\/"},{"@type":"ListItem","position":3,"name":"\ud83d\udd0d Periksa nomor telepon"}]},{"@type":"WebSite","@id":"https:\/\/truenmbstapp.de\/id\/#website","url":"https:\/\/truenmbstapp.de\/id","name":"NumBuster","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numbuster.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id-ID"}]}},"_links":{"self":[{"href":"https:\/\/truenmbstapp.de\/id\/wp-json\/wp\/v2\/help_category\/750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truenmbstapp.de\/id\/wp-json\/wp\/v2\/help_category"}],"about":[{"href":"https:\/\/truenmbstapp.de\/id\/wp-json\/wp\/v2\/taxonomies\/help_category"}],"up":[{"embeddable":true,"href":"https:\/\/truenmbstapp.de\/id\/wp-json\/wp\/v2\/help_category\/744"}],"wp:post_type":[{"href":"https:\/\/truenmbstapp.de\/id\/wp-json\/wp\/v2\/help?help_category=750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}