{"id":5334,"date":"2026-01-29T11:05:01","date_gmt":"2026-01-29T11:05:01","guid":{"rendered":"https:\/\/truenmbstapp.de\/?post_type=help&#038;p=5334"},"modified":"2026-02-02T12:36:51","modified_gmt":"2026-02-02T12:36:51","slug":"what-is-numcy-and-how-to-use-it","status":"publish","type":"help","link":"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/","title":{"rendered":"O que \u00e9 NumCy e como usar"},"content":{"rendered":"\n<p>No NumBuster, voc\u00ea pode usar o <strong>NumCy<\/strong>, a moeda virtual do aplicativo, para desbloquear recursos adicionais e remover limites.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recursos do NumCy<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Consultas ilimitadas<\/strong> \u2014 A capacidade de continuar verificando n\u00fameros de telefone sem restri\u00e7\u00f5es<\/li>\n\n\n\n<li><strong>Opini\u00f5es adicionais<\/strong> \u2014 Novas solicita\u00e7\u00f5es ao NeurOwl quando o limite principal j\u00e1 estiver esgotado<\/li>\n\n\n\n<li><strong>Destacar coment\u00e1rios<\/strong> \u2014 Voc\u00ea pode fixar uma avalia\u00e7\u00e3o selecionada no topo da p\u00e1gina de um n\u00famero de telefone para que informa\u00e7\u00f5es importantes fiquem vis\u00edveis para outros usu\u00e1rios<\/li>\n\n\n\n<li><strong>Amigos em comum<\/strong> \u2014 Saiba qual de seus contatos tamb\u00e9m conhece este n\u00famero de telefone<\/li>\n\n\n\n<li><strong>Personaliza\u00e7\u00e3o da interface<\/strong> \u2014 Personaliza\u00e7\u00e3o da apar\u00eancia visual do aplicativo de acordo com suas prefer\u00eancias<\/li>\n\n\n\n<li><strong>Previs\u00f5es do Theoscope<\/strong> \u2014 Acesse tanto as suas pr\u00f3prias previs\u00f5es quanto as geradas para outros usu\u00e1rios para ajudar na tomada de decis\u00f5es<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Como comprar NumCy<\/h3>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Na <strong>Tela inicial<\/strong> do aplicativo, toque no \u00edcone do <strong>NumCy<\/strong><\/li>\n\n\n\n<li>Selecione <strong>Comprar<\/strong><\/li>\n\n\n\n<li>Escolha a quantidade necess\u00e1ria de moedas<\/li>\n<\/ol>\n\n\n\n<p><em><strong>Nota:<\/strong> Seu saldo atual de NumCy tamb\u00e9m \u00e9 exibido nesta se\u00e7\u00e3o.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No NumBuster, voc\u00ea pode usar o NumCy, a moeda virtual do aplicativo, para desbloquear recursos adicionais e remover limites. Recursos do NumCy Como comprar NumCy Nota: Seu saldo atual de NumCy tamb\u00e9m \u00e9 exibido nesta se\u00e7\u00e3o.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"help_category":[384,418],"help_platform":[],"class_list":["post-5334","help","type-help","status-publish","hentry","help_category-android","help_category-paid-features-android"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 NumCy e como usar - NumBuster<\/title>\n<meta name=\"description\" content=\"NumCy \u00e9 a moeda do NumBuster para remover limites e usar as fun\u00e7\u00f5es do aplicativo quando e como voc\u00ea precisar no seu dia a dia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 NumCy e como usar - NumBuster\" \/>\n<meta property=\"og:description\" content=\"NumCy \u00e9 a moeda do NumBuster para remover limites e usar as fun\u00e7\u00f5es do aplicativo quando e como voc\u00ea precisar no seu dia a dia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/\" \/>\n<meta property=\"og:site_name\" content=\"NumBuster\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T12:36:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/\",\"url\":\"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/\",\"name\":\"O que \u00e9 NumCy e como usar - NumBuster\",\"isPartOf\":{\"@id\":\"https:\/\/numbuster.com\/tr\/#website\"},\"datePublished\":\"2026-01-29T11:05:01+00:00\",\"dateModified\":\"2026-02-02T12:36:51+00:00\",\"description\":\"NumCy \u00e9 a moeda do NumBuster para remover limites e usar as fun\u00e7\u00f5es do aplicativo quando e como voc\u00ea precisar no seu dia a dia.\",\"breadcrumb\":{\"@id\":\"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/numbuster.me\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Central de Ajuda\",\"item\":\"https:\/\/truenmbstapp.de\/pt-pt\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O que \u00e9 NumCy e como usar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/truenmbstapp.de\/pt-pt\/#website\",\"url\":\"https:\/\/truenmbstapp.de\/pt-pt\",\"name\":\"NumBuster\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/numbuster.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 NumCy e como usar - NumBuster","description":"NumCy \u00e9 a moeda do NumBuster para remover limites e usar as fun\u00e7\u00f5es do aplicativo quando e como voc\u00ea precisar no seu dia a dia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 NumCy e como usar - NumBuster","og_description":"NumCy \u00e9 a moeda do NumBuster para remover limites e usar as fun\u00e7\u00f5es do aplicativo quando e como voc\u00ea precisar no seu dia a dia.","og_url":"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/","og_site_name":"NumBuster","article_modified_time":"2026-02-02T12:36:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/","url":"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/","name":"O que \u00e9 NumCy e como usar - NumBuster","isPartOf":{"@id":"https:\/\/numbuster.com\/tr\/#website"},"datePublished":"2026-01-29T11:05:01+00:00","dateModified":"2026-02-02T12:36:51+00:00","description":"NumCy \u00e9 a moeda do NumBuster para remover limites e usar as fun\u00e7\u00f5es do aplicativo quando e como voc\u00ea precisar no seu dia a dia.","breadcrumb":{"@id":"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/truenmbstapp.de\/pt-pt\/help\/android\/paid-features-android\/what-is-numcy-and-how-to-use-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/numbuster.me\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Central de Ajuda","item":"https:\/\/truenmbstapp.de\/pt-pt\/help\/"},{"@type":"ListItem","position":3,"name":"O que \u00e9 NumCy e como usar"}]},{"@type":"WebSite","@id":"https:\/\/truenmbstapp.de\/pt-pt\/#website","url":"https:\/\/truenmbstapp.de\/pt-pt","name":"NumBuster","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numbuster.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/truenmbstapp.de\/pt-pt\/wp-json\/wp\/v2\/help\/5334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truenmbstapp.de\/pt-pt\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/truenmbstapp.de\/pt-pt\/wp-json\/wp\/v2\/types\/help"}],"wp:attachment":[{"href":"https:\/\/truenmbstapp.de\/pt-pt\/wp-json\/wp\/v2\/media?parent=5334"}],"wp:term":[{"taxonomy":"help_category","embeddable":true,"href":"https:\/\/truenmbstapp.de\/pt-pt\/wp-json\/wp\/v2\/help_category?post=5334"},{"taxonomy":"help_platform","embeddable":true,"href":"https:\/\/truenmbstapp.de\/pt-pt\/wp-json\/wp\/v2\/help_platform?post=5334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}