{"id":832,"count":1,"description":"","link":"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/","name":"\ud83d\udecd\ufe0f \u00dcr\u00fcn &amp; Hizmet kartlar\u0131","slug":"products-services-cards-iphone","taxonomy":"help_category","parent":824,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ud83d\udecd\ufe0f \u00dcr\u00fcn &amp; Hizmet kartlar\u0131 - NumBuster<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\udecd\ufe0f \u00dcr\u00fcn &amp; Hizmet kartlar\u0131 - NumBuster\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/\" \/>\n<meta property=\"og:site_name\" content=\"NumBuster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/\",\"url\":\"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/\",\"name\":\"\ud83d\udecd\ufe0f \u00dcr\u00fcn &amp; Hizmet kartlar\u0131 - NumBuster\",\"isPartOf\":{\"@id\":\"https:\/\/numbuster.com\/tr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/#breadcrumb\"},\"inLanguage\":\"tr-TR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/numbuster.com\/tr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"iPhone\",\"item\":\"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\ud83d\udecd\ufe0f \u00dcr\u00fcn &amp; Hizmet kartlar\u0131\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/truenmbstapp.de\/tr\/#website\",\"url\":\"https:\/\/truenmbstapp.de\/tr\",\"name\":\"NumBuster\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/numbuster.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr-TR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\udecd\ufe0f \u00dcr\u00fcn &amp; Hizmet kartlar\u0131 - NumBuster","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/","og_locale":"tr_TR","og_type":"article","og_title":"\ud83d\udecd\ufe0f \u00dcr\u00fcn &amp; Hizmet kartlar\u0131 - NumBuster","og_url":"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/","og_site_name":"NumBuster","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/","url":"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/","name":"\ud83d\udecd\ufe0f \u00dcr\u00fcn &amp; Hizmet kartlar\u0131 - NumBuster","isPartOf":{"@id":"https:\/\/numbuster.com\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/#breadcrumb"},"inLanguage":"tr-TR"},{"@type":"BreadcrumbList","@id":"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/products-services-cards-iphone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/numbuster.com\/tr\/"},{"@type":"ListItem","position":2,"name":"iPhone","item":"https:\/\/truenmbstapp.de\/tr\/help\/iphone\/"},{"@type":"ListItem","position":3,"name":"\ud83d\udecd\ufe0f \u00dcr\u00fcn &amp; Hizmet kartlar\u0131"}]},{"@type":"WebSite","@id":"https:\/\/truenmbstapp.de\/tr\/#website","url":"https:\/\/truenmbstapp.de\/tr","name":"NumBuster","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numbuster.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr-TR"}]}},"_links":{"self":[{"href":"https:\/\/truenmbstapp.de\/tr\/wp-json\/wp\/v2\/help_category\/832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truenmbstapp.de\/tr\/wp-json\/wp\/v2\/help_category"}],"about":[{"href":"https:\/\/truenmbstapp.de\/tr\/wp-json\/wp\/v2\/taxonomies\/help_category"}],"up":[{"embeddable":true,"href":"https:\/\/truenmbstapp.de\/tr\/wp-json\/wp\/v2\/help_category\/824"}],"wp:post_type":[{"href":"https:\/\/truenmbstapp.de\/tr\/wp-json\/wp\/v2\/help?help_category=832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}