{"id":385,"count":42,"description":"","link":"https:\/\/truenmbstapp.de\/uk\/help\/android\/","name":"Android","slug":"android","taxonomy":"help_category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Android - NumBuster<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truenmbstapp.de\/uk\/help\/android\/\" \/>\n<meta property=\"og:locale\" content=\"uk_UA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Android - NumBuster\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truenmbstapp.de\/uk\/help\/android\/\" \/>\n<meta property=\"og:site_name\" content=\"NumBuster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/truenmbstapp.de\/uk\/help\/android\/\",\"url\":\"https:\/\/truenmbstapp.de\/uk\/help\/android\/\",\"name\":\"Android - NumBuster\",\"isPartOf\":{\"@id\":\"https:\/\/numbuster.com\/tr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/truenmbstapp.de\/uk\/help\/android\/#breadcrumb\"},\"inLanguage\":\"uk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/truenmbstapp.de\/uk\/help\/android\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/truenmbstapp.de\/uk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Android\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/truenmbstapp.de\/uk\/#website\",\"url\":\"https:\/\/truenmbstapp.de\/uk\",\"name\":\"NumBuster\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/numbuster.com\/tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"uk\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Android - NumBuster","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truenmbstapp.de\/uk\/help\/android\/","og_locale":"uk_UA","og_type":"article","og_title":"Android - NumBuster","og_url":"https:\/\/truenmbstapp.de\/uk\/help\/android\/","og_site_name":"NumBuster","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/truenmbstapp.de\/uk\/help\/android\/","url":"https:\/\/truenmbstapp.de\/uk\/help\/android\/","name":"Android - NumBuster","isPartOf":{"@id":"https:\/\/numbuster.com\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/truenmbstapp.de\/uk\/help\/android\/#breadcrumb"},"inLanguage":"uk"},{"@type":"BreadcrumbList","@id":"https:\/\/truenmbstapp.de\/uk\/help\/android\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/truenmbstapp.de\/uk\/"},{"@type":"ListItem","position":2,"name":"Android"}]},{"@type":"WebSite","@id":"https:\/\/truenmbstapp.de\/uk\/#website","url":"https:\/\/truenmbstapp.de\/uk","name":"NumBuster","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numbuster.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"uk"}]}},"_links":{"self":[{"href":"https:\/\/truenmbstapp.de\/uk\/wp-json\/wp\/v2\/help_category\/385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truenmbstapp.de\/uk\/wp-json\/wp\/v2\/help_category"}],"about":[{"href":"https:\/\/truenmbstapp.de\/uk\/wp-json\/wp\/v2\/taxonomies\/help_category"}],"wp:post_type":[{"href":"https:\/\/truenmbstapp.de\/uk\/wp-json\/wp\/v2\/help?help_category=385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}